{"id":2081,"date":"2013-04-29T20:55:00","date_gmt":"2013-04-29T20:55:00","guid":{"rendered":"http:\/\/rf.podcastfixit.com\/index.php\/2013\/04\/29\/les-deputes-liberaux-de-laval-sopposen\/"},"modified":"2015-06-01T19:41:52","modified_gmt":"2015-06-01T19:41:52","slug":"les-deputes-liberaux-de-laval-sopposen","status":"publish","type":"post","link":"https:\/\/newscoverage.org\/index.php\/2013\/04\/29\/les-deputes-liberaux-de-laval-sopposen\/","title":{"rendered":"Les d\u00e9put\u00e9s lib\u00e9raux de Laval s&#8217;opposent cat\u00e9goriquement le projet de loi 14"},"content":{"rendered":"<p>\n<b><i>\u00abLe respect est tr\u00e8s important&#8221;<\/i><\/b><\/p>\n<p><b>Par Robert Frank<\/b><br \/>\n<a href=\"http:\/\/www.thesuburban.com\/\">www.thesuburban.com<\/a><\/p>\n<p>Les quatre d\u00e9put\u00e9s lib\u00e9raux \u00e9lus pour repr\u00e9senter les circonscriptions de Laval \u00e0 Qu\u00e9bec ont uni leurs forces, le 19 avril afin de &#8220;d\u00e9plorer l&#8217;approche coercitive du Parti qu\u00e9b\u00e9cois &nbsp;qui enl\u00e8ve des les droits et l&#8217;augmente le fardeau administratif pesant sur les entreprises [qu\u00e9b\u00e9coises].&#8221;<\/p>\n<p>\u00abIl est clair que c&#8217;est notre intention de voter contre le projet de loi 14,&nbsp;parce que apr\u00e8s avoir lu 86 m\u00e9moires et d&#8217;\u00e9couter 76 pr\u00e9sentations lors d&#8217;une audition parlementaire, la plupart des t\u00e9moins ont clairement&nbsp;trouv\u00e9&nbsp;insatisfaisante l&#8217;approche de la&nbsp;ministre de la&nbsp;langue&nbsp;Diane de Courcy&nbsp;\u00bb,&nbsp;de dire Guy Ouellette&nbsp;le&nbsp;pr\u00e9sident du&nbsp;caucus lib\u00e9ral de&nbsp;Laval&nbsp;au cours d&#8217;une entrevue avec le journal&nbsp;<i>The Suburban&nbsp;<\/i>\u00bb<i style=\"font-family: Georgia, 'Times New Roman', serif;\">.<\/i><\/p>\n<p>Le d\u00e9put\u00e9 de Chomedey a \u00e9mis la d\u00e9claration conjointe faisant front commun avec ses coll\u00e8gues lib\u00e9raux Francine Charbonneau (Mille-\u00celes), Gilles Ouimet (Fabre) et Jean Rousselle (Vimont).<\/p>\n<p>Ils ont condamn\u00e9 les mesures coercitives qui impr\u00e8gnent le projet de loi en notant que \u00ab le Barreau du Qu\u00e9bec, des entreprises, des conseils scolaires, des parents, des municipalit\u00e9s et des citoyens provenant de partout au Qu\u00e9bec ont exprim\u00e9 de fortes r\u00e9ticences&nbsp;\u00bb.<\/p>\n<p>\u00ab Il est donc inconcevable pour le Parti lib\u00e9ral du Qu\u00e9bec de voter pour un projet de loi qui pr\u00e9voit :<\/p>\n<p>\u2022 la nomination par le ministre des inspecteurs qui agiront sous le contr\u00f4le du ministre et qui deviendra un service de police politique de la langue ;<\/p>\n<p>\u2022 judiciariser des plaintes \u00e0 l&#8217;Office qu\u00e9b\u00e9cois de la langue fran\u00e7aise ;<\/p>\n<p>\u2022 limiter l&#8217;inscription des \u00e9tudiants fran\u00e7ais aux&nbsp;c\u00e9geps&nbsp;anglais ;<\/p>\n<p>\u2022 retirer l&#8217;exemption qui a&nbsp;de longue date&nbsp;permis&nbsp;aux enfants des militaires canadiens de suivre leurs \u00e9tudes en anglais ;<\/p>\n<p>\u2022 retirer le statut bilingue de certaines municipalit\u00e9s ;<\/p>\n<p>\u2022 augmenter sensiblement la paperasserie et le fardeau administratif des entreprises qu\u00e9becoises ; et<\/p>\n<p>\u2022 menacer les droits accord\u00e9s en vertu de la Charte des droits et libert\u00e9s du Qu\u00e9bec \u00bb.<\/p>\n<p>\u00ab Le respect est primordial, a soulign\u00e9 M. Ouellette. Tous les Qu\u00e9b\u00e9cois ont des droits et nous devons les prot\u00e9ger, plut\u00f4t que de les diviser&nbsp;\u00bb.<\/p>\n<div>\n<\/div>\n<p>  (function(i,s,o,g,r,a,m){i[&#8216;GoogleAnalyticsObject&#8217;]=r;i[r]=i[r]||function(){<br \/>\n  (i[r].q=i[r].q||[]).push(arguments)},i[r].l=1*new Date();a=s.createElement(o),<br \/>\n  m=s.getElementsByTagName(o)[0];a.async=1;a.src=g;m.parentNode.insertBefore(a,m)<br \/>\n  })(window,document,&#8217;script&#8217;,&#8217;\/\/www.google-analytics.com\/analytics.js&#8217;,&#8217;ga&#8217;);<\/p>\n<p>  ga(&#8216;create&#8217;, &#8216;UA-45892555-1&#8217;, &#8216;robertfrankmedia.blogspot.com&#8217;);<br \/>\n  ga(&#8216;send&#8217;, &#8216;pageview&#8217;);<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abLe respect est tr\u00e8s important&#8221; Par Robert Frank www.thesuburban.com Les quatre d\u00e9put\u00e9s lib\u00e9raux \u00e9lus pour repr\u00e9senter les circonscriptions de Laval \u00e0 Qu\u00e9bec ont uni leurs forces, le 19 avril afin de &#8220;d\u00e9plorer l&#8217;approche coercitive du Parti qu\u00e9b\u00e9cois &nbsp;qui enl\u00e8ve des les droits et l&#8217;augmente le fardeau administratif pesant sur les entreprises [qu\u00e9b\u00e9coises].&#8221; \u00abIl est clair<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2081","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les d\u00e9put\u00e9s lib\u00e9raux de Laval s&#039;opposent cat\u00e9goriquement le projet de loi 14 - Newscoverage<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newscoverage.org\/index.php\/2013\/04\/29\/les-deputes-liberaux-de-laval-sopposen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les d\u00e9put\u00e9s lib\u00e9raux de Laval s&#039;opposent cat\u00e9goriquement le projet de loi 14 - Newscoverage\" \/>\n<meta property=\"og:description\" content=\"\u00abLe respect est tr\u00e8s important&#8221; Par Robert Frank www.thesuburban.com Les quatre d\u00e9put\u00e9s lib\u00e9raux \u00e9lus pour repr\u00e9senter les circonscriptions de Laval \u00e0 Qu\u00e9bec ont uni leurs forces, le 19 avril afin de &#8220;d\u00e9plorer l&#8217;approche coercitive du Parti qu\u00e9b\u00e9cois &nbsp;qui enl\u00e8ve des les droits et l&#8217;augmente le fardeau administratif pesant sur les entreprises [qu\u00e9b\u00e9coises].&#8221; \u00abIl est clair\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newscoverage.org\/index.php\/2013\/04\/29\/les-deputes-liberaux-de-laval-sopposen\/\" \/>\n<meta property=\"og:site_name\" content=\"Newscoverage\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/robert.frank.90834\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-29T20:55:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-01T19:41:52+00:00\" \/>\n<meta name=\"author\" content=\"editor robert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"editor robert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/newscoverage.org\\\/index.php\\\/2013\\\/04\\\/29\\\/les-deputes-liberaux-de-laval-sopposen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/newscoverage.org\\\/index.php\\\/2013\\\/04\\\/29\\\/les-deputes-liberaux-de-laval-sopposen\\\/\"},\"author\":{\"name\":\"editor robert\",\"@id\":\"https:\\\/\\\/newscoverage.org\\\/#\\\/schema\\\/person\\\/fc82a2a747f4a72f7a4833658ab077a3\"},\"headline\":\"Les d\u00e9put\u00e9s lib\u00e9raux de Laval s&#8217;opposent cat\u00e9goriquement le projet de loi 14\",\"datePublished\":\"2013-04-29T20:55:00+00:00\",\"dateModified\":\"2015-06-01T19:41:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/newscoverage.org\\\/index.php\\\/2013\\\/04\\\/29\\\/les-deputes-liberaux-de-laval-sopposen\\\/\"},\"wordCount\":475,\"commentCount\":0,\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/newscoverage.org\\\/index.php\\\/2013\\\/04\\\/29\\\/les-deputes-liberaux-de-laval-sopposen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/newscoverage.org\\\/index.php\\\/2013\\\/04\\\/29\\\/les-deputes-liberaux-de-laval-sopposen\\\/\",\"url\":\"https:\\\/\\\/newscoverage.org\\\/index.php\\\/2013\\\/04\\\/29\\\/les-deputes-liberaux-de-laval-sopposen\\\/\",\"name\":\"Les d\u00e9put\u00e9s lib\u00e9raux de Laval s'opposent cat\u00e9goriquement le projet de loi 14 - Newscoverage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/newscoverage.org\\\/#website\"},\"datePublished\":\"2013-04-29T20:55:00+00:00\",\"dateModified\":\"2015-06-01T19:41:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/newscoverage.org\\\/#\\\/schema\\\/person\\\/fc82a2a747f4a72f7a4833658ab077a3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/newscoverage.org\\\/index.php\\\/2013\\\/04\\\/29\\\/les-deputes-liberaux-de-laval-sopposen\\\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/newscoverage.org\\\/index.php\\\/2013\\\/04\\\/29\\\/les-deputes-liberaux-de-laval-sopposen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/newscoverage.org\\\/index.php\\\/2013\\\/04\\\/29\\\/les-deputes-liberaux-de-laval-sopposen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/newscoverage.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les d\u00e9put\u00e9s lib\u00e9raux de Laval s&#8217;opposent cat\u00e9goriquement le projet de loi 14\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/newscoverage.org\\\/#website\",\"url\":\"https:\\\/\\\/newscoverage.org\\\/\",\"name\":\"Newscoverage\",\"description\":\"newscoverage.org\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/newscoverage.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/newscoverage.org\\\/#\\\/schema\\\/person\\\/fc82a2a747f4a72f7a4833658ab077a3\",\"name\":\"editor robert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8218f97425a88f0212b8636d21d09c56391445f892db32b08ed4f8e5613c37ac?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8218f97425a88f0212b8636d21d09c56391445f892db32b08ed4f8e5613c37ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8218f97425a88f0212b8636d21d09c56391445f892db32b08ed4f8e5613c37ac?s=96&d=mm&r=g\",\"caption\":\"editor robert\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/robert.frank.90834\"],\"url\":\"https:\\\/\\\/newscoverage.org\\\/index.php\\\/author\\\/editor-robert\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les d\u00e9put\u00e9s lib\u00e9raux de Laval s'opposent cat\u00e9goriquement le projet de loi 14 - Newscoverage","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newscoverage.org\/index.php\/2013\/04\/29\/les-deputes-liberaux-de-laval-sopposen\/","og_locale":"en_US","og_type":"article","og_title":"Les d\u00e9put\u00e9s lib\u00e9raux de Laval s'opposent cat\u00e9goriquement le projet de loi 14 - Newscoverage","og_description":"\u00abLe respect est tr\u00e8s important&#8221; Par Robert Frank www.thesuburban.com Les quatre d\u00e9put\u00e9s lib\u00e9raux \u00e9lus pour repr\u00e9senter les circonscriptions de Laval \u00e0 Qu\u00e9bec ont uni leurs forces, le 19 avril afin de &#8220;d\u00e9plorer l&#8217;approche coercitive du Parti qu\u00e9b\u00e9cois &nbsp;qui enl\u00e8ve des les droits et l&#8217;augmente le fardeau administratif pesant sur les entreprises [qu\u00e9b\u00e9coises].&#8221; \u00abIl est clair","og_url":"https:\/\/newscoverage.org\/index.php\/2013\/04\/29\/les-deputes-liberaux-de-laval-sopposen\/","og_site_name":"Newscoverage","article_author":"https:\/\/www.facebook.com\/robert.frank.90834","article_published_time":"2013-04-29T20:55:00+00:00","article_modified_time":"2015-06-01T19:41:52+00:00","author":"editor robert","twitter_card":"summary_large_image","twitter_misc":{"Written by":"editor robert","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/newscoverage.org\/index.php\/2013\/04\/29\/les-deputes-liberaux-de-laval-sopposen\/#article","isPartOf":{"@id":"https:\/\/newscoverage.org\/index.php\/2013\/04\/29\/les-deputes-liberaux-de-laval-sopposen\/"},"author":{"name":"editor robert","@id":"https:\/\/newscoverage.org\/#\/schema\/person\/fc82a2a747f4a72f7a4833658ab077a3"},"headline":"Les d\u00e9put\u00e9s lib\u00e9raux de Laval s&#8217;opposent cat\u00e9goriquement le projet de loi 14","datePublished":"2013-04-29T20:55:00+00:00","dateModified":"2015-06-01T19:41:52+00:00","mainEntityOfPage":{"@id":"https:\/\/newscoverage.org\/index.php\/2013\/04\/29\/les-deputes-liberaux-de-laval-sopposen\/"},"wordCount":475,"commentCount":0,"inLanguage":"en-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/newscoverage.org\/index.php\/2013\/04\/29\/les-deputes-liberaux-de-laval-sopposen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/newscoverage.org\/index.php\/2013\/04\/29\/les-deputes-liberaux-de-laval-sopposen\/","url":"https:\/\/newscoverage.org\/index.php\/2013\/04\/29\/les-deputes-liberaux-de-laval-sopposen\/","name":"Les d\u00e9put\u00e9s lib\u00e9raux de Laval s'opposent cat\u00e9goriquement le projet de loi 14 - Newscoverage","isPartOf":{"@id":"https:\/\/newscoverage.org\/#website"},"datePublished":"2013-04-29T20:55:00+00:00","dateModified":"2015-06-01T19:41:52+00:00","author":{"@id":"https:\/\/newscoverage.org\/#\/schema\/person\/fc82a2a747f4a72f7a4833658ab077a3"},"breadcrumb":{"@id":"https:\/\/newscoverage.org\/index.php\/2013\/04\/29\/les-deputes-liberaux-de-laval-sopposen\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newscoverage.org\/index.php\/2013\/04\/29\/les-deputes-liberaux-de-laval-sopposen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/newscoverage.org\/index.php\/2013\/04\/29\/les-deputes-liberaux-de-laval-sopposen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newscoverage.org\/"},{"@type":"ListItem","position":2,"name":"Les d\u00e9put\u00e9s lib\u00e9raux de Laval s&#8217;opposent cat\u00e9goriquement le projet de loi 14"}]},{"@type":"WebSite","@id":"https:\/\/newscoverage.org\/#website","url":"https:\/\/newscoverage.org\/","name":"Newscoverage","description":"newscoverage.org","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newscoverage.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Person","@id":"https:\/\/newscoverage.org\/#\/schema\/person\/fc82a2a747f4a72f7a4833658ab077a3","name":"editor robert","image":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/8218f97425a88f0212b8636d21d09c56391445f892db32b08ed4f8e5613c37ac?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8218f97425a88f0212b8636d21d09c56391445f892db32b08ed4f8e5613c37ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8218f97425a88f0212b8636d21d09c56391445f892db32b08ed4f8e5613c37ac?s=96&d=mm&r=g","caption":"editor robert"},"sameAs":["https:\/\/www.facebook.com\/robert.frank.90834"],"url":"https:\/\/newscoverage.org\/index.php\/author\/editor-robert\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/newscoverage.org\/index.php\/wp-json\/wp\/v2\/posts\/2081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newscoverage.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newscoverage.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newscoverage.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newscoverage.org\/index.php\/wp-json\/wp\/v2\/comments?post=2081"}],"version-history":[{"count":1,"href":"https:\/\/newscoverage.org\/index.php\/wp-json\/wp\/v2\/posts\/2081\/revisions"}],"predecessor-version":[{"id":5177,"href":"https:\/\/newscoverage.org\/index.php\/wp-json\/wp\/v2\/posts\/2081\/revisions\/5177"}],"wp:attachment":[{"href":"https:\/\/newscoverage.org\/index.php\/wp-json\/wp\/v2\/media?parent=2081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newscoverage.org\/index.php\/wp-json\/wp\/v2\/categories?post=2081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newscoverage.org\/index.php\/wp-json\/wp\/v2\/tags?post=2081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}